{"id":76236,"date":"2023-10-04T12:30:13","date_gmt":"2023-10-04T10:30:13","guid":{"rendered":"https:\/\/bien-etreiris.ch\/ratgeber-klarheit-beratung\/gesunder-lebensstil\/naehrstoffe\/zwischen-getreide\/pseudogetreide\/quinoa\/quinoa\/"},"modified":"2023-10-04T17:41:33","modified_gmt":"2023-10-04T15:41:33","slug":"bienfaits","status":"publish","type":"page","link":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/gesunder-lebensstil\/naehrstoffe\/lebensmittel\/zwischen-getreide\/pseudogetreide\/quinoa\/bienfaits\/","title":{"rendered":"SO GESUND &#8230;"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":1,"featured_media":55728,"parent":57511,"menu_order":2930,"comment_status":"closed","ping_status":"closed","template":"page-with-child.php","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-76236","page","type-page","status-publish","post-password-required","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SO GESUND ... - WOHLBEFINDEN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/gesunder-lebensstil\/naehrstoffe\/zwischen-getreide\/pseudogetreide\/quinoa\/bienfaits\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SO GESUND ... - WOHLBEFINDEN\" \/>\n<meta property=\"og:description\" content=\"Es gibt keinen Textauszug, da dies ein gesch\u00fctzter Beitrag ist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/gesunder-lebensstil\/naehrstoffe\/zwischen-getreide\/pseudogetreide\/quinoa\/bienfaits\/\" \/>\n<meta property=\"og:site_name\" content=\"WOHLBEFINDEN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bienetreiris\/\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-04T15:41:33+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"30\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/gesunder-lebensstil\\\/naehrstoffe\\\/zwischen-getreide\\\/pseudogetreide\\\/quinoa\\\/bienfaits\\\/\",\"url\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/gesunder-lebensstil\\\/naehrstoffe\\\/zwischen-getreide\\\/pseudogetreide\\\/quinoa\\\/bienfaits\\\/\",\"name\":\"SO GESUND ... - WOHLBEFINDEN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/#website\"},\"datePublished\":\"2023-10-04T10:30:13+00:00\",\"dateModified\":\"2023-10-04T15:41:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/gesunder-lebensstil\\\/naehrstoffe\\\/zwischen-getreide\\\/pseudogetreide\\\/quinoa\\\/bienfaits\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/\",\"name\":\"Bien-\u00eatre Iris\",\"description\":\"IHRE Gesundheit ist uns wichtig\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SO GESUND ... - WOHLBEFINDEN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/gesunder-lebensstil\/naehrstoffe\/zwischen-getreide\/pseudogetreide\/quinoa\/bienfaits\/","og_locale":"de_DE","og_type":"article","og_title":"SO GESUND ... - WOHLBEFINDEN","og_description":"Es gibt keinen Textauszug, da dies ein gesch\u00fctzter Beitrag ist.","og_url":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/gesunder-lebensstil\/naehrstoffe\/zwischen-getreide\/pseudogetreide\/quinoa\/bienfaits\/","og_site_name":"WOHLBEFINDEN","article_publisher":"https:\/\/www.facebook.com\/bienetreiris\/","article_modified_time":"2023-10-04T15:41:33+00:00","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"30\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/gesunder-lebensstil\/naehrstoffe\/zwischen-getreide\/pseudogetreide\/quinoa\/bienfaits\/","url":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/gesunder-lebensstil\/naehrstoffe\/zwischen-getreide\/pseudogetreide\/quinoa\/bienfaits\/","name":"SO GESUND ... - WOHLBEFINDEN","isPartOf":{"@id":"https:\/\/bien-etreiris.ch\/de\/#website"},"datePublished":"2023-10-04T10:30:13+00:00","dateModified":"2023-10-04T15:41:33+00:00","breadcrumb":{"@id":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/gesunder-lebensstil\/naehrstoffe\/zwischen-getreide\/pseudogetreide\/quinoa\/bienfaits\/#breadcrumb"},"inLanguage":"de"},{"@type":"WebSite","@id":"https:\/\/bien-etreiris.ch\/de\/#website","url":"https:\/\/bien-etreiris.ch\/de\/","name":"Bien-\u00eatre Iris","description":"IHRE Gesundheit ist uns wichtig","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bien-etreiris.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/76236","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/comments?post=76236"}],"version-history":[{"count":4,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/76236\/revisions"}],"predecessor-version":[{"id":76244,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/76236\/revisions\/76244"}],"up":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/57511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/media\/55728"}],"wp:attachment":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/media?parent=76236"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}