{"id":63787,"date":"2023-01-06T15:40:59","date_gmt":"2023-01-06T13:40:59","guid":{"rendered":"https:\/\/bien-etreiris.ch\/ratgeber-klarheit-beratung\/natuerliche-heilmittel\/pflanzenheilkunde\/heilpflanzen\/yam\/"},"modified":"2024-03-31T11:38:30","modified_gmt":"2024-03-31T09:38:30","slug":"yam","status":"publish","type":"page","link":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/natuerliche-heilmittel\/pflanzenheilkunde\/heilpflanzen\/yam\/","title":{"rendered":"YAM"},"content":{"rendered":"","protected":true},"excerpt":{"rendered":"","protected":true},"author":1,"featured_media":55728,"parent":56557,"menu_order":4182,"comment_status":"closed","ping_status":"closed","template":"page-with-child.php","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-63787","page","type-page","status-publish","post-password-required","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>YAM - WOHLBEFINDEN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/natuerliche-heilmittel\/pflanzenheilkunde\/heilpflanzen\/yam\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"YAM - WOHLBEFINDEN\" \/>\n<meta property=\"og:description\" content=\"Es gibt keinen Textauszug, da dies ein gesch\u00fctzter Beitrag ist.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/natuerliche-heilmittel\/pflanzenheilkunde\/heilpflanzen\/yam\/\" \/>\n<meta property=\"og:site_name\" content=\"WOHLBEFINDEN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bienetreiris\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-31T09:38:30+00:00\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/natuerliche-heilmittel\\\/pflanzenheilkunde\\\/heilpflanzen\\\/yam\\\/\",\"url\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/natuerliche-heilmittel\\\/pflanzenheilkunde\\\/heilpflanzen\\\/yam\\\/\",\"name\":\"YAM - WOHLBEFINDEN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/#website\"},\"datePublished\":\"2023-01-06T13:40:59+00:00\",\"dateModified\":\"2024-03-31T09:38:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/natuerliche-heilmittel\\\/pflanzenheilkunde\\\/heilpflanzen\\\/yam\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/\",\"name\":\"Bien-\u00eatre Iris\",\"description\":\"IHRE Gesundheit ist uns wichtig\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"YAM - WOHLBEFINDEN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/natuerliche-heilmittel\/pflanzenheilkunde\/heilpflanzen\/yam\/","og_locale":"de_DE","og_type":"article","og_title":"YAM - WOHLBEFINDEN","og_description":"Es gibt keinen Textauszug, da dies ein gesch\u00fctzter Beitrag ist.","og_url":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/natuerliche-heilmittel\/pflanzenheilkunde\/heilpflanzen\/yam\/","og_site_name":"WOHLBEFINDEN","article_publisher":"https:\/\/www.facebook.com\/bienetreiris\/","article_modified_time":"2024-03-31T09:38:30+00:00","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/natuerliche-heilmittel\/pflanzenheilkunde\/heilpflanzen\/yam\/","url":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/natuerliche-heilmittel\/pflanzenheilkunde\/heilpflanzen\/yam\/","name":"YAM - WOHLBEFINDEN","isPartOf":{"@id":"https:\/\/bien-etreiris.ch\/de\/#website"},"datePublished":"2023-01-06T13:40:59+00:00","dateModified":"2024-03-31T09:38:30+00:00","breadcrumb":{"@id":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/natuerliche-heilmittel\/pflanzenheilkunde\/heilpflanzen\/yam\/#breadcrumb"},"inLanguage":"de"},{"@type":"WebSite","@id":"https:\/\/bien-etreiris.ch\/de\/#website","url":"https:\/\/bien-etreiris.ch\/de\/","name":"Bien-\u00eatre Iris","description":"IHRE Gesundheit ist uns wichtig","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bien-etreiris.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/63787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/comments?post=63787"}],"version-history":[{"count":1,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/63787\/revisions"}],"predecessor-version":[{"id":63789,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/63787\/revisions\/63789"}],"up":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/56557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/media\/55728"}],"wp:attachment":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/media?parent=63787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}