{"id":56557,"date":"2022-06-11T10:16:43","date_gmt":"2022-06-11T08:16:43","guid":{"rendered":"https:\/\/bien-etreiris.ch\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/plantes-medicinales\/"},"modified":"2022-07-07T12:55:05","modified_gmt":"2022-07-07T10:55:05","slug":"heilpflanzen","status":"publish","type":"page","link":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/natuerliche-heilmittel\/pflanzenheilkunde\/heilpflanzen\/","title":{"rendered":"HEILPFLANZEN"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":55911,"parent":52607,"menu_order":4852,"comment_status":"closed","ping_status":"closed","template":"page-with-child.php","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-56557","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>HEILPFLANZEN - WOHLBEFINDEN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"HEILPFLANZEN - WOHLBEFINDEN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/\" \/>\n<meta property=\"og:site_name\" content=\"WOHLBEFINDEN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bienetreiris\/\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-07T10:55:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2022\/06\/Acceuil-Plantes-medicinales.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/pflanzenheilkunde\\\/heilpflanzen\\\/\",\"url\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/pflanzenheilkunde\\\/heilpflanzen\\\/\",\"name\":\"HEILPFLANZEN - WOHLBEFINDEN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/pflanzenheilkunde\\\/heilpflanzen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/pflanzenheilkunde\\\/heilpflanzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/bien-etreiris.ch\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Acceuil-Plantes-medicinales.jpg\",\"datePublished\":\"2022-06-11T08:16:43+00:00\",\"dateModified\":\"2022-07-07T10:55:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/pflanzenheilkunde\\\/heilpflanzen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/pflanzenheilkunde\\\/heilpflanzen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/pflanzenheilkunde\\\/heilpflanzen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/bien-etreiris.ch\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Acceuil-Plantes-medicinales.jpg\",\"contentUrl\":\"https:\\\/\\\/bien-etreiris.ch\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/Acceuil-Plantes-medicinales.jpg\",\"width\":500,\"height\":333},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/pflanzenheilkunde\\\/heilpflanzen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RATGEBER &#038; KLARHEIT\",\"item\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"PFLANZENHEILKUNDE\",\"item\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/ratgeber-klarheit-beratung\\\/pflanzenheilkunde\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"HEILPFLANZEN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/\",\"name\":\"Bien-\u00eatre Iris\",\"description\":\"IHRE Gesundheit ist uns wichtig\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"HEILPFLANZEN - WOHLBEFINDEN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/","og_locale":"de_DE","og_type":"article","og_title":"HEILPFLANZEN - WOHLBEFINDEN","og_url":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/","og_site_name":"WOHLBEFINDEN","article_publisher":"https:\/\/www.facebook.com\/bienetreiris\/","article_modified_time":"2022-07-07T10:55:05+00:00","og_image":[{"width":500,"height":333,"url":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2022\/06\/Acceuil-Plantes-medicinales.jpg","type":"image\/jpeg"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/","url":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/","name":"HEILPFLANZEN - WOHLBEFINDEN","isPartOf":{"@id":"https:\/\/bien-etreiris.ch\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/#primaryimage"},"image":{"@id":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/#primaryimage"},"thumbnailUrl":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2022\/06\/Acceuil-Plantes-medicinales.jpg","datePublished":"2022-06-11T08:16:43+00:00","dateModified":"2022-07-07T10:55:05+00:00","breadcrumb":{"@id":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/#primaryimage","url":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2022\/06\/Acceuil-Plantes-medicinales.jpg","contentUrl":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2022\/06\/Acceuil-Plantes-medicinales.jpg","width":500,"height":333},{"@type":"BreadcrumbList","@id":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/heilpflanzen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bien-etreiris.ch\/de\/"},{"@type":"ListItem","position":2,"name":"RATGEBER &#038; KLARHEIT","item":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/"},{"@type":"ListItem","position":3,"name":"PFLANZENHEILKUNDE","item":"https:\/\/bien-etreiris.ch\/de\/ratgeber-klarheit-beratung\/pflanzenheilkunde\/"},{"@type":"ListItem","position":4,"name":"HEILPFLANZEN"}]},{"@type":"WebSite","@id":"https:\/\/bien-etreiris.ch\/de\/#website","url":"https:\/\/bien-etreiris.ch\/de\/","name":"Bien-\u00eatre Iris","description":"IHRE Gesundheit ist uns wichtig","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bien-etreiris.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/56557","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/comments?post=56557"}],"version-history":[{"count":2,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/56557\/revisions"}],"predecessor-version":[{"id":56560,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/56557\/revisions\/56560"}],"up":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/52607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/media\/55911"}],"wp:attachment":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/media?parent=56557"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}