{"id":89207,"date":"2024-09-12T10:08:30","date_gmt":"2024-09-12T08:08:30","guid":{"rendered":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png"},"modified":"2024-09-12T10:08:30","modified_gmt":"2024-09-12T08:08:30","slug":"ras-el-hanout-2-2","status":"inherit","type":"attachment","link":"https:\/\/bien-etreiris.ch\/de\/produktpraesentation\/gesundes-leben\/gesunde-lebensmittel\/zutaten-wohlbefinden\/gewuerze\/gewurze-aus-marokko\/ras-el-hanout-2-2\/","title":{"rendered":"Ras el hanout"},"author":1,"featured_media":0,"comment_status":"","ping_status":"closed","template":"","meta":{"_acf_changed":false,"ngg_post_thumbnail":0},"class_list":["post-89207","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ras el hanout - WOHLBEFINDEN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ras el hanout - WOHLBEFINDEN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png\" \/>\n<meta property=\"og:site_name\" content=\"WOHLBEFINDEN\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/bienetreiris\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png\" \/>\n\t<meta property=\"og:image:width\" content=\"85\" \/>\n\t<meta property=\"og:image:height\" content=\"85\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ras-el-hanout.png\",\"url\":\"https:\\\/\\\/bien-etreiris.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ras-el-hanout.png\",\"name\":\"Ras el hanout - WOHLBEFINDEN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/#website\"},\"datePublished\":\"2024-09-12T08:08:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ras-el-hanout.png#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/bien-etreiris.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ras-el-hanout.png\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/Ras-el-hanout.png#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRODUKTPR\u00c4SENTATION\",\"item\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/produktpraesentation\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"GESUNDES LEBEN\",\"item\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/produktpraesentation\\\/gesundes-leben\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"GESUNDE LEBENSMITTEL\",\"item\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/produktpraesentation\\\/gesundes-leben\\\/gesunde-lebensmittel\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"ZUTATEN\",\"item\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/produktpraesentation\\\/gesundes-leben\\\/gesunde-lebensmittel\\\/zutaten-wohlbefinden\\\/\"},{\"@type\":\"ListItem\",\"position\":6,\"name\":\"GEW\u00dcRZE\",\"item\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/produktpraesentation\\\/gesundes-leben\\\/gesunde-lebensmittel\\\/zutaten-wohlbefinden\\\/gewuerze\\\/\"},{\"@type\":\"ListItem\",\"position\":7,\"name\":\"&#8211;GEW\u00dcRZE AUS MAROKKO&#8211;\",\"item\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/produktpraesentation\\\/gesundes-leben\\\/gesunde-lebensmittel\\\/zutaten-wohlbefinden\\\/gewuerze\\\/gewurze-aus-marokko\\\/\"},{\"@type\":\"ListItem\",\"position\":8,\"name\":\"Ras el hanout\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/\",\"name\":\"Bien-\u00eatre Iris\",\"description\":\"IHRE Gesundheit ist uns wichtig\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/bien-etreiris.ch\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ras el hanout - WOHLBEFINDEN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png","og_locale":"de_DE","og_type":"article","og_title":"Ras el hanout - WOHLBEFINDEN","og_url":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png","og_site_name":"WOHLBEFINDEN","article_publisher":"https:\/\/www.facebook.com\/bienetreiris\/","og_image":[{"width":85,"height":85,"url":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png","type":"image\/png"}],"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png","url":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png","name":"Ras el hanout - WOHLBEFINDEN","isPartOf":{"@id":"https:\/\/bien-etreiris.ch\/de\/#website"},"datePublished":"2024-09-12T08:08:30+00:00","breadcrumb":{"@id":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/bien-etreiris.ch\/de\/"},{"@type":"ListItem","position":2,"name":"PRODUKTPR\u00c4SENTATION","item":"https:\/\/bien-etreiris.ch\/de\/produktpraesentation\/"},{"@type":"ListItem","position":3,"name":"GESUNDES LEBEN","item":"https:\/\/bien-etreiris.ch\/de\/produktpraesentation\/gesundes-leben\/"},{"@type":"ListItem","position":4,"name":"GESUNDE LEBENSMITTEL","item":"https:\/\/bien-etreiris.ch\/de\/produktpraesentation\/gesundes-leben\/gesunde-lebensmittel\/"},{"@type":"ListItem","position":5,"name":"ZUTATEN","item":"https:\/\/bien-etreiris.ch\/de\/produktpraesentation\/gesundes-leben\/gesunde-lebensmittel\/zutaten-wohlbefinden\/"},{"@type":"ListItem","position":6,"name":"GEW\u00dcRZE","item":"https:\/\/bien-etreiris.ch\/de\/produktpraesentation\/gesundes-leben\/gesunde-lebensmittel\/zutaten-wohlbefinden\/gewuerze\/"},{"@type":"ListItem","position":7,"name":"&#8211;GEW\u00dcRZE AUS MAROKKO&#8211;","item":"https:\/\/bien-etreiris.ch\/de\/produktpraesentation\/gesundes-leben\/gesunde-lebensmittel\/zutaten-wohlbefinden\/gewuerze\/gewurze-aus-marokko\/"},{"@type":"ListItem","position":8,"name":"Ras el hanout"}]},{"@type":"WebSite","@id":"https:\/\/bien-etreiris.ch\/de\/#website","url":"https:\/\/bien-etreiris.ch\/de\/","name":"Bien-\u00eatre Iris","description":"IHRE Gesundheit ist uns wichtig","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/bien-etreiris.ch\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png'><img loading=\"lazy\" decoding=\"async\" width=\"85\" height=\"85\" src=\"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png\" class=\"attachment-medium size-medium\" alt=\"\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/png","media_details":{"width":85,"height":85,"file":"2024\/09\/Ras-el-hanout.png","filesize":22107,"sizes":{"slider-thumb":{"file":"Ras-el-hanout-85x50.png","width":85,"height":50,"filesize":11890,"mime_type":"image\/png","source_url":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout-85x50.png"},"full":{"file":"Ras-el-hanout.png","width":85,"height":85,"mime_type":"image\/png","source_url":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":89214,"source_url":"https:\/\/bien-etreiris.ch\/wp-content\/uploads\/2024\/09\/Ras-el-hanout.png","_links":{"self":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/media\/89207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/comments?post=89207"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":89214,"href":"https:\/\/bien-etreiris.ch\/de\/wp-json\/wp\/v2\/pages\/89214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}